{"id":6694,"date":"2025-10-14T12:06:31","date_gmt":"2025-10-14T10:06:31","guid":{"rendered":"https:\/\/blueberrybloom.com\/returns-refunds\/"},"modified":"2025-12-17T18:13:19","modified_gmt":"2025-12-17T16:13:19","slug":"rueckgaben-erstattungen","status":"publish","type":"page","link":"https:\/\/blueberrybloom.com\/de\/rueckgaben-erstattungen\/","title":{"rendered":"R\u00fcckgaben &amp; Erstattungen"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6694\" class=\"elementor elementor-6694 elementor-6600\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74c1d77 e-con-full e-flex e-con e-parent\" data-id=\"74c1d77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b3ae014 e-con-full e-flex e-con e-child\" data-id=\"b3ae014\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ed0d525 e-con-full e-flex e-con e-child\" data-id=\"ed0d525\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-131b569 e-con-full e-flex e-con e-child\" data-id=\"131b569\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f3316c1 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"f3316c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f19bf02 elementor-widget__width-auto elementor-icon-list--layout-inline elementor-list-item-link-inline elementor-mobile-align-center elementor-widget elementor-widget-icon-list\" data-id=\"f19bf02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/blueberrybloom.com\/de\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Startseite<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/blueberrybloom.com\/de\/rueckgaben-erstattungen\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00fcckgaben &amp; Erstattungen<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00e59a0 elementor-widget elementor-widget-heading\" data-id=\"00e59a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Berry easy R\u00fcckgabe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb6cfa3 elementor-widget elementor-widget-heading\" data-id=\"eb6cfa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Weil es einfach sein sollte, das richtige Paar zu finden.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ec756c e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"8ec756c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1de5d4 elementor-widget elementor-widget-image\" data-id=\"c1de5d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"511\" height=\"440\" src=\"https:\/\/blueberrybloom.com\/wp-content\/uploads\/2025\/10\/Blueberry-Bloom-Returns-and-Refunds.avif\" class=\"attachment-full size-full wp-image-6623\" alt=\"Customer preparing to return Blueberry Bloom earrings using eco packaging, showing safe and sustainable return process.\" srcset=\"https:\/\/blueberrybloom.com\/wp-content\/uploads\/2025\/10\/Blueberry-Bloom-Returns-and-Refunds.avif 511w, https:\/\/blueberrybloom.com\/wp-content\/uploads\/2025\/10\/Blueberry-Bloom-Returns-and-Refunds-300x258.avif 300w\" sizes=\"auto, (max-width: 511px) 100vw, 511px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3e02091 e-flex e-con-boxed e-con e-parent\" data-id=\"3e02091\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-004a1bf elementor-widget elementor-widget-text-editor\" data-id=\"004a1bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"604\" data-end=\"792\">Bei Blueberry Bloom ist es mir wichtig, dass du deinen Schmuck liebst. Wenn etwas nicht ganz passt, soll die R\u00fcckgabe oder der Umtausch unkompliziert und stressfrei sein \u2014 keine langen Formulare, keine Hektik. Nur ein klarer Ablauf und freundlicher Support. <\/p><h6><strong data-start=\"802\" data-end=\"819\"><br>Kurz\u00fcbersicht<\/strong><\/h6><ul data-start=\"821\" data-end=\"1228\"><li data-start=\"821\" data-end=\"874\"><p data-start=\"823\" data-end=\"874\"><em><strong data-start=\"823\" data-end=\"841\">R\u00fcckgabefrist<\/strong>: 14 Kalendertage ab Erhalt der Lieferung<\/em><\/p><\/li><li data-start=\"875\" data-end=\"935\"><p data-start=\"877\" data-end=\"935\"><em><strong data-start=\"877\" data-end=\"892\">Bedingungen<\/strong>: Ungetragen, unbesch\u00e4digt und in der Originalverpackung<\/em><\/p><\/li><li data-start=\"936\" data-end=\"1009\"><p data-start=\"938\" data-end=\"1009\"><em><strong data-start=\"938\" data-end=\"953\">Ausnahmen<\/strong>: Sonderanfertigungen k\u00f6nnen nur bei M\u00e4ngeln zur\u00fcckgegeben werden<\/em><\/p><\/li><li data-start=\"1010\" data-end=\"1088\"><p data-start=\"1012\" data-end=\"1088\"><em><strong data-start=\"1012\" data-end=\"1031\">R\u00fcckversand<\/strong>: Kosten tr\u00e4gt der K\u00e4ufer (au\u00dfer bei besch\u00e4digter oder falscher Ware)<\/em><\/p><\/li><li data-start=\"1089\" data-end=\"1161\"><p data-start=\"1091\" data-end=\"1161\"><em><strong data-start=\"1091\" data-end=\"1103\">Erstattungen<\/strong>: Erfolgen innerhalb von <strong data-start=\"1121\" data-end=\"1142\">3\u20135 Werktagen<\/strong> nach Pr\u00fcfung der R\u00fccksendung<\/em><\/p><\/li><li data-start=\"1162\" data-end=\"1228\"><p data-start=\"1164\" data-end=\"1228\"><em><strong data-start=\"1164\" data-end=\"1176\">Kontakt<\/strong>: <a href=\"mailto:info@blueberrybloom.com\">info@blueberrybloom.com <\/a>\u2013 R\u00fccksendeadresse siehe unten<\/em><\/p><\/li><\/ul><p data-start=\"1230\" data-end=\"1294\"><em>Versandinformationen: Siehe meine Seite <strong data-start=\"1259\" data-end=\"1282\"><a class=\"decorated-link\" href=\"https:\/\/blueberrybloom.com\/de\/versand-lieferung\/\" rel=\"noopener\" data-start=\"1258\" data-end=\"1286\">\u201eVersand &amp; Lieferung\u201c<\/a><\/strong> <\/em><\/p><h6><strong data-start=\"1304\" data-end=\"1329\"><br>Wer kann zur\u00fcckgeben &amp; wann?<\/strong><\/h6><p data-start=\"1331\" data-end=\"1550\">Du kannst deinen Schmuck innerhalb von <strong data-start=\"1378\" data-end=\"1398\">14 Kalendertagen<\/strong> nach Lieferung zur\u00fcckgeben oder umtauschen.<br data-start=\"1411\" data-end=\"1414\"><strong data-start=\"1444\" data-end=\"1471\">Bitte kontaktiere mich <\/strong>vor der R\u00fccksendung zuerst \u2013 so k\u00f6nnen wir deine R\u00fcckgabe freigeben und dich durch den schnellen Ablauf begleiten.<\/p><h6><strong data-start=\"1560\" data-end=\"1586\"><br>R\u00fcckgabebedingungen<\/strong><\/h6><p data-start=\"1588\" data-end=\"1626\">Ich akzeptiere R\u00fccksendungen nur, wenn die Artikel:<\/p><ul data-start=\"1627\" data-end=\"1733\"><li data-start=\"1627\" data-end=\"1657\"><p data-start=\"1629\" data-end=\"1657\"><strong data-start=\"1629\" data-end=\"1650\">ungetragen und unbesch\u00e4digt<\/strong> sind<\/p><\/li><li data-start=\"1658\" data-end=\"1733\"><p data-start=\"1660\" data-end=\"1733\">sich in der <strong data-start=\"1669\" data-end=\"1691\">Originalverpackung <\/strong>befinden (einschlie\u00dflich Schmuckkarte, Beutel und Box)<\/p><\/li><\/ul><p data-start=\"1735\" data-end=\"1862\">Bitte lege deinem Paket<strong data-start=\"1755\" data-end=\"1800\"> deinen Namen, deine Bestellnummer und den R\u00fccksendegrund<\/strong> bei \u2013 so kann ich deine Erstattung schneller bearbeiten.<\/p><h6><strong data-start=\"1872\" data-end=\"1886\"><br>Ausnahmen<\/strong><\/h6><p data-start=\"1888\" data-end=\"2109\">Da jedes personalisierte Schmuckst\u00fcck individuell f\u00fcr dich <strong data-start=\"1941\" data-end=\"1965\">handgefertigt<\/strong> wird, sind ma\u00dfgefertigte Ohrringe vom Umtausch und <strong data-start=\"1970\" data-end=\"1988\">von der R\u00fcckgabe ausgeschlossen<\/strong> \u2013 es sei denn, sie kommen <strong data-start=\"2009\" data-end=\"2032\">besch\u00e4digt oder fehlerhaft <\/strong>bei dir an.<br data-start=\"2033\" data-end=\"2036\">Sollte mir ein Fehler unterlaufen, k\u00fcmmere ich mich schnell und kostenlos um eine L\u00f6sung.<\/p><h6><strong data-start=\"2119\" data-end=\"2148\"><br>Wer tr\u00e4gt die R\u00fccksendekosten?<\/strong><\/h6><p data-start=\"2150\" data-end=\"2318\">Die Kosten f\u00fcr die R\u00fccksendung tr\u00e4gt die Kundin bzw. der Kunde.<br data-start=\"2189\" data-end=\"2192\">Sollte deine Bestellung jedoch <strong data-start=\"2223\" data-end=\"2234\">besch\u00e4digt<\/strong> oder <strong data-start=\"2238\" data-end=\"2251\">falsch<\/strong> geliefert worden sein, \u00fcbernehme ich die R\u00fccksendekosten oder sende dir <strong data-start=\"2295\" data-end=\"2315\">kostenfrei Ersatz<\/strong>.<\/p><h6><strong data-start=\"2328\" data-end=\"2367\"><br>So beantragst du eine R\u00fcckgabe oder einen Umtausch<\/strong><\/h6><ol data-start=\"2369\" data-end=\"2626\"><li data-start=\"2369\" data-end=\"2447\"><p data-start=\"2372\" data-end=\"2447\"><strong data-start=\"2372\" data-end=\"2385\">E-Mail:<\/strong> <a href=\"mailto:info@blueberrybloom.com\">info@blueberrybloom.com<\/a> oder nutze mein <strong data-start=\"2425\" data-end=\"2441\"><a class=\"decorated-link\" href=\"https:\/\/blueberrybloom.com\/de\/kontakt\/\" rel=\"noopener\" data-start=\"2424\" data-end=\"2445\">Kontaktformular.<\/a><\/strong><\/p><\/li><li data-start=\"2448\" data-end=\"2543\"><p data-start=\"2451\" data-end=\"2543\">Gib deine Bestellnummer an und teile mir mit, ob du eine <strong data-start=\"2464\" data-end=\"2480\"><strong data-start=\"2512\" data-end=\"2522\">R\u00fcckgabe<\/strong><\/strong> oder einen <strong data-start=\"2529\" data-end=\"2541\">Umtausch<\/strong> w\u00fcnschst.<\/p><\/li><li data-start=\"2544\" data-end=\"2626\"><p data-start=\"2547\" data-end=\"2626\">Ich sende dir daraufhin weitere Anweisungen und best\u00e4tige ggf. Verf\u00fcgbarkeit oder Lieferzeiten bei einem Umtausch.<\/p><\/li><\/ol><p data-start=\"2628\" data-end=\"2716\">Nach der Genehmigung verpacke bitte den Artikel sicher und sende ihn an die unten angegebene R\u00fccksendeadresse.<\/p><h6><strong data-start=\"2726\" data-end=\"2744\"><br>R\u00fccksendeadresse<\/strong><\/h6><p data-start=\"2746\" data-end=\"2814\">Auhofstra\u00dfe 116\/1\/8, 1130 Wien<br>\u00d6sterreich<\/p><h6><strong data-start=\"2824\" data-end=\"2843\"><br>R\u00fcckerstattungszeitraum<\/strong><\/h6><p data-start=\"2845\" data-end=\"2880\">Nachdem deine R\u00fccksendung bei mir eingetroffen ist:<\/p><ul data-start=\"2881\" data-end=\"3015\"><li data-start=\"2881\" data-end=\"2927\"><p data-start=\"2883\" data-end=\"2927\">Ich pr\u00fcfe sie innerhalb von <strong data-start=\"2904\" data-end=\"2925\">1\u20132 Werktagen.<\/strong><\/p><\/li><li data-start=\"2928\" data-end=\"3015\"><p data-start=\"2930\" data-end=\"3015\">R\u00fcckerstattungen werden innerhalb von <strong data-start=\"2992\" data-end=\"3013\">3\u20135 Werktagen <\/strong>auf deine <strong data-start=\"2957\" data-end=\"2984\">urspr\u00fcngliche Zahlungsmethode <\/strong>ausgezahlt.<\/p><\/li><\/ul><p data-start=\"3017\" data-end=\"3097\">(Einige Banken oder Zahlungsanbieter k\u00f6nnen zus\u00e4tzliche Zeit f\u00fcr die Gutschrift ben\u00f6tigen.)<\/p><h6><strong data-start=\"3107\" data-end=\"3137\"><br>Besch\u00e4digte oder falsche Artikel<\/strong><\/h6><p data-start=\"3139\" data-end=\"3260\">Wenn deine Ohrringe <strong data-start=\"3163\" data-end=\"3174\">besch\u00e4digt<\/strong> oder <strong data-start=\"3178\" data-end=\"3196\">nicht wie bestellt <\/strong>ankommen, schreibe mir bitte innerhalb von <strong data-start=\"3221\" data-end=\"3233\">48 Stunden<\/strong> nach Erhalt eine E-Mail und f\u00fcge folgende Informationen bei:<\/p><ul data-start=\"3261\" data-end=\"3368\"><li data-start=\"3261\" data-end=\"3286\"><p data-start=\"3263\" data-end=\"3286\">Deine <strong data-start=\"3268\" data-end=\"3284\">Bestellnummer<\/strong><\/p><\/li><li data-start=\"3287\" data-end=\"3327\"><p data-start=\"3289\" data-end=\"3327\"><strong data-start=\"3289\" data-end=\"3299\">Fotos<\/strong> der Verpackung und des Artikels<\/p><\/li><li data-start=\"3328\" data-end=\"3368\"><p data-start=\"3330\" data-end=\"3368\">Eine <strong data-start=\"3332\" data-end=\"3353\">kurze Beschreibung<\/strong> des Problems<\/p><\/li><\/ul><p data-start=\"3370\" data-end=\"3460\">Ich pr\u00fcfe den Fall und l\u00f6se ihn so schnell wie m\u00f6glich \u2013 durch <strong data-start=\"3423\" data-end=\"3457\">Ersatz, Reparatur oder R\u00fcckerstattung.<\/strong><\/p><h6><strong data-start=\"3470\" data-end=\"3483\"><br>Umtausch<\/strong><\/h6><p data-start=\"3485\" data-end=\"3638\">Wenn du dein Schmuckst\u00fcck gegen ein anderes Design tauschen m\u00f6chtest, erw\u00e4hne dies bitte bereits in deiner ersten E-Mail. Ich pr\u00fcfe die Verf\u00fcgbarkeit, reserviere dein neues Paar und teile dir die n\u00e4chsten Schritte mit.<\/p><h6><strong data-start=\"3648\" data-end=\"3672\"><br>Rechtliches &amp; Letzte Aktualisierung<\/strong><\/h6><p data-start=\"3674\" data-end=\"3808\"><strong data-start=\"3674\" data-end=\"3684\">Inhaber<\/strong>: Blueberry Bloom \u2013 siehe <strong data-start=\"3712\" data-end=\"3723\"><a class=\"decorated-link\" href=\"https:\/\/blueberrybloom.com\/de\/imprint\/\" rel=\"noopener\" data-start=\"3711\" data-end=\"3727\">Impressum<\/a><\/strong> sowie <strong data-start=\"3733\" data-end=\"3755\"><a class=\"decorated-link\" href=\"https:\/\/blueberrybloom.com\/de\/terms-and-conditions\/\" rel=\"noopener\" data-start=\"3732\" data-end=\"3759\">Allgemeine Gesch\u00e4ftsbedingungen<\/a><\/strong><br data-start=\"3759\" data-end=\"3762\"><strong data-start=\"3762\" data-end=\"3774\">Datenschutz<\/strong>: siehe <strong data-start=\"3784\" data-end=\"3802\"><a class=\"decorated-link\" href=\"https:\/\/blueberrybloom.com\/de\/privacy-statement-eu\/\" rel=\"noopener\" data-start=\"3783\" data-end=\"3806\">Datenschutzerkl\u00e4rung<\/a><\/strong><\/p><p data-start=\"3810\" data-end=\"3845\"><strong data-start=\"3810\" data-end=\"3827\">Letzte Aktualisierung:<\/strong> 14. Oktober 2025<\/p><h6><strong data-start=\"3855\" data-end=\"3867\"><br>Mini-FAQ<\/strong><\/h6><p data-start=\"3869\" data-end=\"3982\"><strong data-start=\"3869\" data-end=\"3910\">Wie lange habe ich Zeit, einen Artikel zur\u00fcckzugeben?<\/strong><br data-start=\"3910\" data-end=\"3913\">Du hast ab dem Tag der Lieferung <strong data-start=\"3922\" data-end=\"3942\">14 Kalendertage<\/strong> Zeit, um deine Bestellung zur\u00fcckzusenden.<\/p><p data-start=\"3984\" data-end=\"4089\"><strong data-start=\"3984\" data-end=\"4005\">Sind R\u00fccksendungen kostenlos?<\/strong><br data-start=\"4005\" data-end=\"4008\">Die R\u00fccksendekosten tr\u00e4gt der K\u00e4ufer, au\u00dfer der Artikel ist fehlerhaft oder wurde falsch geliefert.<\/p><p data-start=\"4091\" data-end=\"4266\"><strong data-start=\"4091\" data-end=\"4121\">Wann erhalte ich meine R\u00fcckerstattung?<\/strong><br data-start=\"4121\" data-end=\"4124\">R\u00fcckerstattungen erfolgen innerhalb von<strong data-start=\"4150\" data-end=\"4171\"> 3\u20135 Werktagen<\/strong>, nachdem ich deine R\u00fccksendung erhalten und gepr\u00fcft habe. (Bitte beachte, dass es je nach Bank etwas l\u00e4nger dauern kann, bis der Betrag auf deinem Konto erscheint.)<\/p><p data-start=\"4268\" data-end=\"4394\"><strong data-start=\"4268\" data-end=\"4305\">Kann ich statt einer R\u00fcckgabe auch umtauschen?<\/strong><br data-start=\"4305\" data-end=\"4308\">Ja! Schreibe mir bitte zuerst eine E-Mail, damit ich die Verf\u00fcgbarkeit best\u00e4tigen und dich durch den Umtauschprozess f\u00fchren kann. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Startseite R\u00fcckgaben &amp; Erstattungen Berry easy R\u00fcckgabe Weil es einfach sein sollte, das richtige Paar zu finden. Bei Blueberry Bloom ist es mir wichtig, dass du deinen Schmuck liebst. Wenn etwas nicht ganz passt, soll die R\u00fcckgabe oder der Umtausch unkompliziert und stressfrei sein \u2014 keine langen Formulare, keine Hektik. Nur ein klarer Ablauf und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_titles_title":"R\u00fcckgaben & Erstattungen | 14-Tage-R\u00fcckgaberecht","_seopress_titles_desc":"Erfahre alles \u00fcber R\u00fcckgabe und Erstattung bei Blueberry Bloom \u2013 mit 14 Tagen R\u00fcckgabefrist, einfachem Ablauf und schneller Abwicklung. ","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-6694","page","type-page","status-publish"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"Petra","author_link":"https:\/\/blueberrybloom.com\/de\/author\/blissful3286\/"},"uagb_comment_info":0,"uagb_excerpt":"Startseite R\u00fcckgaben &amp; Erstattungen Berry easy R\u00fcckgabe Weil es einfach sein sollte, das richtige Paar zu finden. Bei Blueberry Bloom ist es mir wichtig, dass du deinen Schmuck liebst. Wenn etwas nicht ganz passt, soll die R\u00fcckgabe oder der Umtausch unkompliziert und stressfrei sein \u2014 keine langen Formulare, keine Hektik. Nur ein klarer Ablauf und&hellip;","_links":{"self":[{"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/pages\/6694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/comments?post=6694"}],"version-history":[{"count":2,"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/pages\/6694\/revisions"}],"predecessor-version":[{"id":9138,"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/pages\/6694\/revisions\/9138"}],"wp:attachment":[{"href":"https:\/\/blueberrybloom.com\/de\/wp-json\/wp\/v2\/media?parent=6694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}